{"id":4420,"date":"2023-02-16T00:35:45","date_gmt":"2023-02-16T00:35:45","guid":{"rendered":"https://live-placemaking-community.pantheonsite.io/?page_id=4420"},"modified":"2023-07-11T15:14:42","modified_gmt":"2023-07-11T15:14:42","slug":"mentorship-program","status":"publish","type":"page","link":"https://placemakingcommunity.ca/mentorship-program/","title":{"rendered":"Mentorship Page"},"content":{"rendered":"\n\n<div id=\"anvil-wyswyg-block_9bf2654e601de71a547b09567783fe62\" class=\" anvil-wyswyg\">\n\n    <div class=\"row row-center\">\n    <div class=\"columns-10 content-container\">\n        \n        <div class=\"contents\">\n             <h4 style=\"text-align: left\"><strong>Nos possibilités d'apprentissage par les pairs s'appuient sur les principes suivants :</strong></h4>\n<ul style=\"text-align: left\">\n<li> Le mentorat est relationnel ; nous apprenons et nous nous épanouissons en interagissant avec les autres.</li>\n<li>Les gens n'ont pas besoin d'être responsabilisés, ils sont déjà puissants.</li>\n<li>Nous avons des compétences, des connaissances et des expériences différentes ; nous apprenons tous ensemble.</li>\n<li>Les personnes ont besoin d'opportunités et d'être exposées à de nouvelles idées pour développer leur pouvoir.</li>\n<li>Nous sommes des pairs qui marchent les uns à côté des autres. Nous sommes courageux quand nous parlons et, aussi, quand nous écoutons</li>\n</ul>\n<p style=\"text-align: left\"><em>Ces principes clés ont été élaborés sous la direction de <a href=\"http://www.jaypitter.com/\">Jay Pitter Placemaking</a>.</em></p>\n                    </div>\n\n    </div>\n    </div>\n    <style>\n        #anvil-wyswyg-block_9bf2654e601de71a547b09567783fe62 {\n            color:#000000;\n            background: ;\n            padding-top: 0px;\n            padding-bottom: 0px;\n        }\n         #anvil-wyswyg-block_9bf2654e601de71a547b09567783fe62 .row  {\n            justify-content:flex-end;\n        }\n    </style>\n</div>\n\n\r\n<div id=\"intro-block_202cb4a1b49eb0870270df6a64e38275\" class=\"centered-intro intro aligncenter    wave\r\n\r\n\">\r\n\r\n    <div class=\"row row-center\">\r\n\r\n        <div class=\"centered-intro columns-8 content-container\">\r\n\r\n            <div class=\"headings\">\r\n                                   <h6>Opportunité d'apprentissage par les pairs</h6>\r\n\r\n               \r\n\r\n               <h2>Programme de mentorat</h2>\r\n\r\n        </div>\r\n\r\n        <div class=\"contents\">\r\n         <p>Depuis 2021, l'équipe IHO de l'Institut urbain du Canada offre un programme de mentorat en collaboration avec notre équipe de partenaires. À ce jour, ce programme a soutenu le travail de plus de 50 organisations financées dans le cadre de l'Initiative des communautés en santé. Le programme de mentorat offre la possibilité de travailler individuellement avec un praticien expérimenté pendant trois mois afin d'explorer ensemble des idées ou des défis. Le programme de mentorat permet d'entretenir un espace commun de recherche et d'exploration qui peut évoluer et se développer au fil du temps. </p>\r\n\r\n             </div>\r\n</div>\r\n</div>\r\n\r\n\r\n</div>\r\n\r\n<style>\r\n    #intro-block_202cb4a1b49eb0870270df6a64e38275 {\r\n        background: #f0f6f7;\r\n        padding-top: 60px;\r\n        padding-bottom: 0px;\r\n\r\n        margin-top: 70px;\r\n        margin-bottom: 40px;\r\n    }\r\n\r\n    \r\n</style>\r\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":20,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-4420","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https://yoast.com/product/yoast-seo-wordpress/ -->\n<title>Mentorship Page | Canada&#039;s Placemaking Community</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\">\n<link rel=\"canonical\" href=\"https://placemakingcommunity.ca/fr/mentorship-program/\">\n<meta property=\"og:locale\" content=\"en_US\">\n<meta property=\"og:type\" content=\"article\">\n<meta property=\"og:title\" content=\"Mentorship Page | Canada&#039;s Placemaking Community\">\n<meta property=\"og:url\" content=\"https://placemakingcommunity.ca/fr/mentorship-program/\">\n<meta property=\"og:site_name\" content=\"La communauté canadienne de l&#039;aménagement du territoire\">\n<meta property=\"article:modified_time\" content=\"2023-07-11T15:14:42+00:00\">\n<meta name=\"twitter:card\" content=\"summary_large_image\">\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https://schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https://placemakingcommunity.ca/fr/mentorship-program/\",\"url\":\"https://placemakingcommunity.ca/fr/mentorship-program/\",\"name\":\"Mentorship Page | Canada&#039;s Placemaking Community\",\"isPartOf\":{\"@id\":\"https://placemakingcommunity.ca/fr/#website\"},\"datePublished\":\"2023-02-16T00:35:45+00:00\",\"dateModified\":\"2023-07-11T15:14:42+00:00\",\"breadcrumb\":{\"@id\":\"https://placemakingcommunity.ca/fr/mentorship-program/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https://placemakingcommunity.ca/fr/mentorship-program/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https://placemakingcommunity.ca/fr/mentorship-program/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https://placemakingcommunity.ca/fr/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mentorship Page\"}]},{\"@type\":\"WebSite\",\"@id\":\"https://placemakingcommunity.ca/fr/#website\",\"url\":\"https://placemakingcommunity.ca/fr\",\"name\":\"Canada&#039;s Placemaking Community\",\"description\":\"\",\"publisher\":{\"@id\":\"https://placemakingcommunity.ca/fr/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https://placemakingcommunity.ca/fr/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https://placemakingcommunity.ca/fr/#organization\",\"name\":\"Canada’s Placemaking Community\",\"url\":\"https://placemakingcommunity.ca/fr\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https://placemakingcommunity.ca/fr/#/schema/logo/image/\",\"url\":\"https://placemakingcommunity.ca/fr/wp-content/uploads/2022/07/Logo-New.svg\",\"contentUrl\":\"https://placemakingcommunity.ca/fr/wp-content/uploads/2022/07/Logo-New.svg\",\"width\":125,\"height\":100,\"caption\":\"Canada’s Placemaking Community\"},\"image\":{\"@id\":\"https://placemakingcommunity.ca/fr/#/schema/logo/image/\"},\"sameAs\":[\"https://www.instagram.com/placemaking.community/\",\"https://www.youtube.com/playlist?list=PL0owufaCfNuFSxJx2KS4e41s5Hn42yDXd\"]}]}</script>\n<!-- / Yoast SEO plugin. -->","yoast_head_json":{"title":"Mentorship Page | Canada&#039;s Placemaking Community","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://placemakingcommunity.ca/mentorship-program/","og_locale":"en_US","og_type":"article","og_title":"Mentorship Page | Canada&#039;s Placemaking Community","og_url":"https://placemakingcommunity.ca/mentorship-program/","og_site_name":"Canada&#039;s Placemaking Community","article_modified_time":"2023-07-11T15:14:42+00:00","twitter_card":"summary_large_image","schema":{"@context":"https://schema.org","@graph":[{"@type":"WebPage","@id":"https://placemakingcommunity.ca/mentorship-program/","url":"https://placemakingcommunity.ca/fr/mentorship-program/","name":"Mentorship Page | Canada&#039;s Placemaking Community","isPartOf":{"@id":"https://placemakingcommunity.ca/#website"},"datePublished":"2023-02-16T00:35:45+00:00","dateModified":"2023-07-11T15:14:42+00:00","breadcrumb":{"@id":"https://placemakingcommunity.ca/mentorship-program/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https://placemakingcommunity.ca/mentorship-program/"]}]},{"@type":"BreadcrumbList","@id":"https://placemakingcommunity.ca/mentorship-program/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https://placemakingcommunity.ca/"},{"@type":"ListItem","position":2,"name":"Mentorship Page"}]},{"@type":"WebSite","@id":"https://placemakingcommunity.ca/#website","url":"https://placemakingcommunity.ca/fr","name":"Canada&#039;s Placemaking Community","description":"","publisher":{"@id":"https://placemakingcommunity.ca/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://placemakingcommunity.ca/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https://placemakingcommunity.ca/#organization","name":"Canada’s Placemaking Community","url":"https://placemakingcommunity.ca/fr","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https://placemakingcommunity.ca/#/schema/logo/image/","url":"https://placemakingcommunity.ca/fr/wp-content/uploads/2022/07/Logo-New.svg","contentUrl":"https://placemakingcommunity.ca/wp-content/uploads/2022/07/Logo-New.svg","width":125,"height":100,"caption":"Canada’s Placemaking Community"},"image":{"@id":"https://placemakingcommunity.ca/#/schema/logo/image/"},"sameAs":["https://www.instagram.com/placemaking.community/","https://www.youtube.com/playlist?list=PL0owufaCfNuFSxJx2KS4e41s5Hn42yDXd"]}]}},"_links":{"self":[{"href":"https://placemakingcommunity.ca/wp-json/wp/v2/pages/4420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://placemakingcommunity.ca/wp-json/wp/v2/pages"}],"about":[{"href":"https://placemakingcommunity.ca/wp-json/wp/v2/types/page"}],"author":[{"embeddable":true,"href":"https://placemakingcommunity.ca/wp-json/wp/v2/users/6"}],"replies":[{"embeddable":true,"href":"https://placemakingcommunity.ca/wp-json/wp/v2/comments?post=4420"}],"version-history":[{"count":0,"href":"https://placemakingcommunity.ca/wp-json/wp/v2/pages/4420/revisions"}],"wp:attachment":[{"href":"https://placemakingcommunity.ca/wp-json/wp/v2/media?parent=4420"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}